{"id":4379,"date":"2022-12-26T10:00:00","date_gmt":"2022-12-26T08:00:00","guid":{"rendered":"https:\/\/www.guatemalatransportservice.com\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/"},"modified":"2026-03-29T10:04:41","modified_gmt":"2026-03-29T08:04:41","slug":"comment-se-rendre-de-flores-a-antigua-au-guatemala","status":"publish","type":"post","link":"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/","title":{"rendered":"Comment se rendre de Flores \u00e0 Antigua, au Guatemala."},"content":{"rendered":"\n<p><strong><span class=\"tadv-color\" style=\"color:#05164d\">Vous pouvez vous rendre de Flores \u00e0 Antigua en navette partag\u00e9e, en bus de luxe, en transfert priv\u00e9 ou en voiture de location.<\/span><\/strong><\/p>\n\n\n<p style=\"color:#555555;font-size:14px\"><em>R\u00e9vis\u00e9 par <a href=\"https:\/\/www.guatemalatransportservice.com\/fr\/a-propos-de-nous\/\">Jean N\u00e1jera, Expert en Industrie du Transport<\/a><\/em><\/p>\n\n\n<p>Antigua est une ville coloniale captivante encadr\u00e9e par deux volcans dans la r\u00e9gion sud du Guatemala. C&rsquo;est un lieu charg\u00e9 d&rsquo;histoire et de culture, mais le v\u00e9ritable tr\u00e9sor d&rsquo;Antigua r\u00e9side \u00e9galement dans la richesse de sa nature !<\/p>\n\n<p>La ville color\u00e9e d&rsquo;Antigua est entour\u00e9e de for\u00eats luxuriantes et de nombreuses plantations de caf\u00e9. Ces plantations de caf\u00e9 sont \u00e9galement devenues des attractions populaires pour les excursions d&rsquo;une journ\u00e9e, o\u00f9 vous pouvez visiter et en apprendre davantage sur le caf\u00e9 guat\u00e9malt\u00e8que !<\/p>\n\n<p>En outre, les charmantes rues \u00e9troites et pav\u00e9es d&rsquo;Antigua sont bord\u00e9es de march\u00e9s en plein air anim\u00e9s et de petits caf\u00e9s et restaurants branch\u00e9s. C&rsquo;est le cadre id\u00e9al pour explorer et plonger dans la culture locale ou pour d\u00e9guster la d\u00e9licieuse cuisine guat\u00e9malt\u00e8que !<\/p>\n\n<p>Et si vous \u00eates plut\u00f4t adepte des activit\u00e9s de plein air, les paysages et les volcans environnants vous permettront \u00e9galement de vivre une aventure inoubliable !<\/p>\n\n<p>Vous pouvez <a href=\"https:\/\/www.getyourguide.com\/antigua-guatemala-l1619\/pacaya-volcano-trek-t53571\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;placement=content-top&amp;cmp=GuatemalaTransport-flores-to-antigua-guatemala\" target=\"_blank\" rel=\"noopener\">r\u00e9server une excursion guid\u00e9e d&rsquo;une journ\u00e9e<\/a> ou participer \u00e0 une randonn\u00e9e sur le volcan comme cette <a href=\"https:\/\/www.getyourguide.com\/antigua-guatemala-l1619\/pacaya-volcano-trek-t53571\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;placement=content-top&amp;cmp=GuatemalaTransport-flores-to-antigua-guatemala\" target=\"_blank\" rel=\"noopener\">randonn\u00e9e guid\u00e9e sur le volcan Pacaya<\/a>! Vous aurez l&rsquo;occasion unique de faire une randonn\u00e9e \u00e0 travers la superbe for\u00eat de pins et de d\u00e9couvrir certaines des vues les plus magnifiques d&rsquo;Antigua !<\/p>\n\n<p>Alors, <a href=\"https:\/\/www.getyourguide.com\/antigua-guatemala-l1619\/pacaya-volcano-trek-t53571\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;placement=content-top&amp;cmp=GuatemalaTransport-flores-to-antigua-guatemala\" target=\"_blank\" rel=\"noopener\">r\u00e9servez votre place sur ce circuit d\u00e8s aujourd&rsquo;hui<\/a>, et ne ratez pas la beaut\u00e9 d&rsquo;Antigua !<\/p>\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/availability.frame\" data-gyg-tour-id=\"53571\" data-gyg-locale-code=\"en-US\" data-gyg-currency=\"USD\" data-gyg-widget=\"availability\" data-gyg-theme=\"light\" data-gyg-variant=\"horizontal\" data-gyg-partner-id=\"RJQ408Z\" data-gyg-cmp=\"GuatemalaTransport-flores-to-antigua-guatemala\" data-gyg-placement=\"content-top\"><\/div>\n\n<div class=\"wp-block-group quick-answer is-layout-flow wp-block-group-is-layout-flow\" style=\"border-left-color:#2ecc71;border-left-width:4px;background-color:#f0faf4;padding-top:16px;padding-right:20px;padding-bottom:16px;padding-left:20px\">\n\n<p style=\"font-size:16px;font-weight:700\">\u26a1 R\u00e9ponse Rapide<\/p>\n\n\n<p style=\"font-size:15px\">Vous pouvez voyager de Flores \u00e0 Antigua, au Guatemala. en navette partag\u00e9e, transfert priv\u00e9, bus, voiture de location, vol. Ce guide compare toutes les options avec des prix actualis\u00e9s, des horaires et des conseils de r\u00e9servation pour 2026.<\/p>\n\n<\/div>\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Distance_entre_Flores_et_Antigua\" >Distance entre Flores et Antigua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Options_de_transport_de_Flores_a_Antigua\" >Options de transport de Flores \u00e0 Antigua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Se_rendre_a_Antigua_depuis_Flores\" >Se rendre \u00e0 Antigua depuis Flores<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#1_Navette_partagee_de_Flores_a_Antigua\" >1. Navette partag\u00e9e de Flores \u00e0 Antigua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#2_Bus_Maya_De_Oro_de_Flores_a_Antigua\" >2. Bus Maya De Oro de Flores \u00e0 Antigua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#3_Transfert_prive_de_Flores_a_Antigua\" >3. Transfert priv\u00e9 de Flores \u00e0 Antigua<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#4_Conduire_avec_une_voiture_de_location_de_Flores_a_Antigua\" >4. Conduire avec une voiture de location de Flores \u00e0 Antigua<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Les_meilleures_excursions_dune_journee_a_Antigua_Guatemala\" >Les meilleures excursions d&rsquo;une journ\u00e9e \u00e0 Antigua, Guatemala<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Foire_aux_questions\" >Foire aux questions<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Quel_est_le_moyen_le_moins_cher_de_se_rendre_de_Flores_a_Antigua\" >Quel est le moyen le moins cher de se rendre de Flores \u00e0 Antigua ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Quel_est_le_moyen_le_plus_rapide_de_se_rendre_de_Flores_a_Antigua\" >Quel est le moyen le plus rapide de se rendre de Flores \u00e0 Antigua ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Quel_est_le_moyen_de_transport_le_plus_populaire_pour_se_rendre_a_Antigua_depuis_Flores\" >Quel est le moyen de transport le plus populaire pour se rendre \u00e0 Antigua depuis Flores ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.guatemalatransportservice.com\/fr\/comment-se-rendre-de-flores-a-antigua-au-guatemala\/#Y_a-t-il_un_bus_direct_de_Flores_a_Antigua\" >Y a-t-il un bus direct de Flores \u00e0 Antigua ?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Distance_entre_Flores_et_Antigua\"><\/span>Distance entre Flores et Antigua<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>La distance entre Flores et Antigua est d&rsquo;environ 517 kilom\u00e8tres ou 321 miles. La dur\u00e9e du voyage est d&rsquo;environ 9 heures et 35 minutes en voiture.<\/p>\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m28!1m12!1m3!1d1966227.9195808787!2d-91.06124722592936!3d15.735848623761576!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m13!3e6!4m5!1s0x8f5f8d2155443f5f%3A0x700a4e9563a972!2sFlores%2C%20Guatemala!3m2!1d16.918125099999997!2d-89.8926065!4m5!1s0x85890e74b0250b15%3A0xf786ba2b2903723d!2sAntigua%2C%20Guatemala!3m2!1d14.557296899999999!2d-90.73322329999999!5e0!3m2!1sen!2smk!4v1671700538170!5m2!1sen!2smk\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n<div class=\"wp-block-group info-box-block is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group info-box-block is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"transportation-options-from-cancun-to-tulum\"><span class=\"ez-toc-section\" id=\"Options_de_transport_de_Flores_a_Antigua\"><\/span>Options de transport de Flores \u00e0 Antigua<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Le tableau suivant pr\u00e9sente toutes les <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">options de transport de Flores \u00e0 Antigua<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th><strong>M\u00e9thode<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Dur\u00e9e du voyage<\/strong><\/th><th class=\"has-text-align-center\" data-align=\"center\"><strong>Prix<\/strong><\/th><\/tr><\/thead><tbody><tr><td><a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">Navette partag\u00e9e de Flores \u00e0 Antigua<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\">12 heures<\/td><td class=\"has-text-align-center\" data-align=\"center\">USD 64<\/td><\/tr><tr><td><a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">Bus de luxe Maya De Oro de Flores \u00e0 Antigua<\/a><\/td><td class=\"has-text-align-center\" data-align=\"center\">11-13,5 heures<\/td><td class=\"has-text-align-center\" data-align=\"center\">USD 67-USD 95<\/td><\/tr><tr><td>Transfert priv\u00e9 de Flores \u00e0 Antigua<\/td><td class=\"has-text-align-center\" data-align=\"center\">9 heures 35 minutes<\/td><td class=\"has-text-align-center\" data-align=\"center\">&#8211;<\/td><\/tr><tr><td>Location de voiture de Flores \u00e0 Antigua<\/td><td class=\"has-text-align-center\" data-align=\"center\">9 heures 35 minutes<\/td><td class=\"has-text-align-center\" data-align=\"center\">&#8211;<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"display: flex; justify-content: center; margin: 30px 0;\">\n<iframe loading=\"lazy\" src=\"https:\/\/shrsl.com\/3mds0\" height=\"540\" width=\"380\" style=\"overflow-x: hidden; border: none; border-radius: 15px; box-shadow: 0 2px 10px rgba(0,0,0,0.1);\"><\/iframe>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Se_rendre_a_Antigua_depuis_Flores\"><\/span><strong>Se rendre \u00e0 Antigua depuis Flores<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Navette_partagee_de_Flores_a_Antigua\"><\/span>1. Navette partag\u00e9e de Flores \u00e0 Antigua<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><em><strong><strong>Dur\u00e9e du voyage<\/strong>: 12 heures<\/strong><\/em><\/p>\n\n<p>Un moyen peu co\u00fbteux et pratique de se rendre de Flores \u00e0 Antigua est de prendre une <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">navette partag\u00e9e en van<\/a>!<\/p>\n\n<p>Un billet aller simple dans ces navettes partag\u00e9es co\u00fbte 64 USD, ce qui est un prix tr\u00e8s raisonnable compte tenu de la longue distance que vous allez parcourir.<\/p>\n\n<p>Le voyage en navette partag\u00e9e en van dure 12 heures, ce qui est plus rapide que certaines options de bus. Cependant, il n&rsquo;y a qu&rsquo;un seul d\u00e9part par jour, donc si vous choisissez de vous rendre de Flores \u00e0 Antigua par ce moyen, il est pr\u00e9f\u00e9rable de vous assurer que vos si\u00e8ges sont r\u00e9serv\u00e9s \u00e0 l&rsquo;avance.<\/p>\n\n<p>Comme ce mode de transport est moins fr\u00e9quent, <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">nous vous recommandons de v\u00e9rifier la disponibilit\u00e9 de vos dates pr\u00e9vues \u00e0 temps et d&rsquo;acheter vos billets en ligne !<\/a><\/p>\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Heure de d\u00e9part<\/th><th class=\"has-text-align-center\" data-align=\"center\">Heure d&rsquo;arriv\u00e9e<\/th><th class=\"has-text-align-center\" data-align=\"center\">Dur\u00e9e<\/th><th class=\"has-text-align-center\" data-align=\"center\">Prix par personne<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">06:00 AM<\/td><td class=\"has-text-align-center\" data-align=\"center\">06:00 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">12 heures<\/td><td class=\"has-text-align-center\" data-align=\"center\">USD 66<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-1024x680.jpg\" alt=\"\" class=\"wp-image-71\" srcset=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-1024x680.jpg 1024w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-300x199.jpg 300w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-768x510.jpg 768w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-735x488.jpg 735w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-335x222.jpg 335w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-347x230.jpg 347w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-520x345.jpg 520w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-640x425.jpg 640w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-960x638.jpg 960w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2-1080x717.jpg 1080w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Bus_Maya_De_Oro_de_Flores_a_Antigua\"><\/span>2. Bus Maya De Oro de Flores \u00e0 Antigua<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><em><strong><strong>Dur\u00e9e du voyage<\/strong>: 11-13,5 heures<\/strong> <\/em><\/p>\n\n<p>Le moyen de <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">transport<\/a> le plus populaire <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">entre Flores et Antigua<\/a> est le bus de luxe Maya De Oro !  <\/p>\n\n<p>Selon le bus que vous prenez, le voyage peut durer entre 11 et 13,5 heures. Cependant, les bus de luxe modernes et bien \u00e9quip\u00e9s de Maya De Oro rendent ce voyage agr\u00e9able et confortable malgr\u00e9 la longue distance.<\/p>\n\n<p>Chaque jour, deux bus de luxe partent de Flores vers Antigua. Ces bus sont \u00e9quip\u00e9s du wifi, de la climatisation, de si\u00e8ges inclinables et de toilettes \u00e0 bord.<\/p>\n\n<p>Vous pouvez \u00e9galement choisir entre un bus de nuit et un bus de jour en fonction de vos projets de voyage. Cependant, nous vous recommandons de prendre le bus de nuit car vous n&rsquo;aurez pas \u00e0 perdre une journ\u00e9e en bus, et vous pourrez arriver \u00e0 Antigua t\u00f4t le matin, bien repos\u00e9 et pr\u00eat \u00e0 explorer !<\/p>\n\n<p>Ces bus quittent Flores et s&rsquo;arr\u00eatent \u00e0 la gare routi\u00e8re de Guatemala, o\u00f9 vous pouvez changer pour un van partag\u00e9 plus compact qui vous emm\u00e8nera \u00e0 Antigua.<\/p>\n\n<p>Si vous pr\u00e9voyez de prendre le bus, vous devez <a href=\"https:\/\/shrsl.com\/3ugei\" target=\"_blank\" rel=\"noopener\">v\u00e9rifier l&rsquo;horaire et r\u00e9server vos places en ligne \u00e0 l&rsquo;avance<\/a> car il n&rsquo;y a que deux d\u00e9parts par jour !<\/p>\n\n<figure class=\"wp-block-table is-style-stripes\"><table><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Heure de d\u00e9part<\/th><th class=\"has-text-align-center\" data-align=\"center\">Heure d&rsquo;arriv\u00e9e<\/th><th class=\"has-text-align-center\" data-align=\"center\">Dur\u00e9e<\/th><th class=\"has-text-align-center\" data-align=\"center\">Prix par personne<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">09:00 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">10:30 AM<\/td><td class=\"has-text-align-center\" data-align=\"center\">13 heures 30 minutes<\/td><td class=\"has-text-align-center\" data-align=\"center\">USD 67<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">09:00 PM<\/td><td class=\"has-text-align-center\" data-align=\"center\">08:00 AM<\/td><td class=\"has-text-align-center\" data-align=\"center\">11 heures<\/td><td class=\"has-text-align-center\" data-align=\"center\">95 USD<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-1024x683.jpg\" alt=\"\" class=\"wp-image-69\" srcset=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-1024x683.jpg 1024w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-300x200.jpg 300w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-768x512.jpg 768w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-735x490.jpg 735w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-335x223.jpg 335w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-347x231.jpg 347w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-520x347.jpg 520w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-640x427.jpg 640w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-960x640.jpg 960w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1-1080x720.jpg 1080w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Flores-to-Antigua-Guatemala1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Transfert_prive_de_Flores_a_Antigua\"><\/span>3. Transfert priv\u00e9 de Flores \u00e0 Antigua<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong><em><em><strong><em><strong><strong>Dur\u00e9e du voyage<\/strong>: 9 heures 35 minutes<\/strong><\/em><\/strong><\/em><\/em><\/strong><\/p>\n\n<p>Si vous voulez que votre voyage de Flores \u00e0 Antigua soit aussi rapide et confortable que possible, nous vous conseillons vivement de r\u00e9server un transfert priv\u00e9 !<\/p>\n\n<p>C&rsquo;est le moyen de transport id\u00e9al puisqu&rsquo;il vous permet de planifier et d&rsquo;organiser vos d\u00e9placements tout en vous offrant des v\u00e9hicules haut de gamme pouvant transporter plus de passagers, un int\u00e9rieur confortable et la climatisation !<\/p>\n\n<p>En particulier, \u00e9tant donn\u00e9 que le voyage vers Antigua dure 9 heures, vous voulez avoir tout cela lorsque vous voyagez.<\/p>\n\n<p>Les navettes priv\u00e9es \u00e9tant plus souples et plus efficaces, vous pouvez vous arr\u00eater \u00e0 certains endroits sur demande pour prendre des photos, aller aux toilettes ou simplement faire une pause pour vous d\u00e9gourdir les jambes.<\/p>\n\n<p>Vous pouvez \u00e9galement choisir votre lieu de ramassage \u00e0 Flores et vous faire conduire \u00e0 Antigua par un chauffeur priv\u00e9 en un peu plus de 9 heures !<\/p>\n\n<p>\u00c0 moins que vous ne voyagiez en solo, ce moyen de transport est le plus simple et le plus abordable pour aller de Flores \u00e0 Antigua si vous acceptez de partager le co\u00fbt entre les membres de votre groupe !<\/p>\n\n<p><strong>Avez-vous besoin d&rsquo;aide pour organiser votre transfert priv\u00e9 de Flores \u00e0 Antigua ?<\/strong><\/p>\n\n<p>Remplissez le formulaire ci-dessous, et l&rsquo;un de nos experts du Guatemala vous contactera !  <\/p>\n\n<p>Nous pouvons \u00e9galement organiser votre <a href=\"https:\/\/mexicotransportservice.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">transport au Mexique<\/a>, au Costa Rica, aux \u00c9tats-Unis et en Colombie !<\/p>\n\n<p>[ARForms id=\u00a0\u00bb100&Prime;]<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-1024x668.jpg\" alt=\"Comment se rendre de Guatemala City &#xE0; Antigua, Guatemala\" class=\"wp-image-73\" srcset=\"https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-1024x668.jpg 1024w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-300x196.jpg 300w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-768x501.jpg 768w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-735x480.jpg 735w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-335x219.jpg 335w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-347x226.jpg 347w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-520x339.jpg 520w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-640x418.jpg 640w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-960x626.jpg 960w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6-1080x705.jpg 1080w, https:\/\/www.guatemalatransportservice.com\/wp-content\/uploads\/2022\/05\/How-to-get-from-Guatemala-City-to-Antigua-Guatemala6.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Conduire_avec_une_voiture_de_location_de_Flores_a_Antigua\"><\/span>4. Conduire avec une voiture de location de Flores \u00e0 Antigua<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><em><strong><strong>Dur\u00e9e du voyage<\/strong>: 9 heures 35 minutes<\/strong><\/em><\/p>\n\n<p>Enfin, si vous voulez aller de Flores \u00e0 Antigua le plus rapidement possible ou si vous voulez explorer le Guatemala, nous vous recommandons de <a href=\"https:\/\/www.guatemalatransportservice.com\/fr\/reservez-votre-voiture-de-location-au-guatemala\/\">louer une voiture<\/a> et de faire un road trip ind\u00e9pendant !<\/p>\n\n<p>Conduire de Flores \u00e0 Antigua peut devenir difficile et \u00e9prouvant, compte tenu de la longue distance. C&rsquo;est loin, et voyager d&rsquo;un point A \u00e0 un point B dans un pays \u00e9tranger n&rsquo;est pas toujours facile.<\/p>\n\n<p>Cependant, si vous d\u00e9cidez quand m\u00eame de prendre cette option, les 9 heures de route entre Flores et Antigua en seront certainement une dont vous vous souviendrez !<\/p>\n\n<p>En louant une voiture, vous pouvez arriver \u00e0 Antigua beaucoup plus rapidement et avoir une libert\u00e9 totale dans l&rsquo;organisation de votre itin\u00e9raire ! De plus, la voiture est le moyen de transport le plus rapide pour se rendre de Flores \u00e0 Antigua.  <\/p>\n\n<p>En outre, voyager de mani\u00e8re ind\u00e9pendante est \u00e9galement le moyen id\u00e9al d&rsquo;explorer la r\u00e9gion et de profiter des vues magnifiques !<\/p>\n\n<p>Et la meilleure partie ? Vous serez surpris de d\u00e9couvrir combien il est simple de trouver et de r\u00e9server une voiture de location bon march\u00e9 \u00e0 Flores !<\/p>\n\n<p><a href=\"https:\/\/www.guatemalatransportservice.com\/fr\/reservez-votre-voiture-de-location-au-guatemala\/\" data-type=\"page\" data-id=\"220\">Nous vous recommandons de faire une r\u00e9servation \u00e0 l&rsquo;avance !<\/a><\/p>\n\n<div id=\"rc-connect-container\"><\/div> \n\n<script id=\"rc-connect\" src=\"https:\/\/www.rentalcars.com\/partners\/integrations\/connect\/connect.js\" data-container=\"rc-connect-container\" data-preflang=\"en\" data-enable-return-checkbox=\"true\" data-rcid=\"universal430\" data-plat=\"guatemalatransportservice\" data-camp=\"Routesarticles\" data-primary=\"05164d\" data-button-size=\"large\"><\/script>\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Les_meilleures_excursions_dune_journee_a_Antigua_Guatemala\"><\/span>Les meilleures excursions d&rsquo;une journ\u00e9e \u00e0 Antigua, Guatemala<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Explorez l&rsquo;un des pays les plus diversifi\u00e9s de la plan\u00e8te avec<a href=\"https:\/\/www.getyourguide.com\/antigua-guatemala-l1619\/pacaya-volcano-trek-t53571\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;placement=content-top&amp;cmp=GuatemalaTransport-flores-to-antigua-guatemala\" target=\"_blank\" rel=\"noopener\"> Get Your Guide &#8211; un<\/a>excellent choix pour les voyageurs qui souhaitent rendre leurs vacances passionnantes et inoubliables !<\/p>\n\n<p>Que vous soyez \u00e0 la recherche de vacances, d&rsquo;un road trip ou d&rsquo;une aventure au Guatemala, Get Your Guide a quelque chose \u00e0 offrir \u00e0 chaque voyageur.  <\/p>\n\n<p>Pr\u00e9parez-vous \u00e0 voir le monde \u00e0 travers et \u00e0 vivre des souvenirs inoubliables en profitant de suggestions personnalis\u00e9es, de voyages guid\u00e9s et de points de rep\u00e8re c\u00e9l\u00e8bres !<\/p>\n\n<p><em>Consultez les widgets suivants pour d\u00e9couvrir d&rsquo;autres <a href=\"https:\/\/www.getyourguide.com\/antigua-guatemala-l1619\/pacaya-volcano-trek-t53571\/?partner_id=RJQ408Z&amp;utm_medium=online_publisher&amp;placement=content-top&amp;cmp=GuatemalaTransport-flores-to-antigua-guatemala\" target=\"_blank\" rel=\"noopener\">excursions d&rsquo;une journ\u00e9e \u00e0 Antigua, au Guatemala<\/a>!<\/em><\/p>\n\n<div data-gyg-href=\"https:\/\/widget.getyourguide.com\/default\/activities.frame\" data-gyg-location-id=\"1619\" data-gyg-locale-code=\"en-US\" data-gyg-widget=\"activities\" data-gyg-number-of-items=\"3\" data-gyg-cmp=\"Guatemala Transport-flores-to-antigua-guatemala\" data-gyg-partner-id=\"RJQ408Z\" data-gyg-placement=\"content-end\"><\/div>\n<!-- GetYourGuide Analytics -->\n\n<script async=\"\" defer=\"defer\" src=\"https:\/\/widget.getyourguide.com\/dist\/pa.umd.production.min.js\" data-gyg-partner-id=\"RJQ408Z\"><\/script>\n\n\n\n<div style=\"display: flex; justify-content: center; margin: 30px 0;\">\n<iframe loading=\"lazy\" src=\"https:\/\/shrsl.com\/3mds0\" height=\"540\" width=\"380\" style=\"overflow-x: hidden; border: none; border-radius: 15px; box-shadow: 0 2px 10px rgba(0,0,0,0.1);\"><\/iframe>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><span class=\"ez-toc-section\" id=\"Foire_aux_questions\"><\/span>Foire aux questions<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1671837468148\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quel_est_le_moyen_le_moins_cher_de_se_rendre_de_Flores_a_Antigua\"><\/span><strong>Quel est le moyen le moins cher de se rendre de Flores \u00e0 Antigua ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Le moyen le moins cher de se rendre de Flores \u00e0 Antigua est la navette partag\u00e9e en van, qui ne co\u00fbte que 64 USD !<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1671837551654\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quel_est_le_moyen_le_plus_rapide_de_se_rendre_de_Flores_a_Antigua\"><\/span><strong>Quel est le moyen le plus rapide de se rendre de Flores \u00e0 Antigua ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Le moyen le plus rapide de se rendre de Flores \u00e0 Antigua est la voiture. Le voyage en voiture prend environ 9 heures et 35 minutes. Pour voyager en voiture, vous pouvez prendre un transfert priv\u00e9 ou louer une voiture !<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1671837809661\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quel_est_le_moyen_de_transport_le_plus_populaire_pour_se_rendre_a_Antigua_depuis_Flores\"><\/span>Quel est le moyen de transport le plus populaire pour se rendre \u00e0 Antigua depuis Flores ?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Le bus de luxe Maya Del Oro est l&rsquo;option la plus populaire pour les voyageurs allant de Flores \u00e0 Antigua !<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1671837581756\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Y_a-t-il_un_bus_direct_de_Flores_a_Antigua\"><\/span>Y a-t-il un bus direct <strong>de Flores \u00e0 Antigua ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Le bus qui part de Flores pour se rendre \u00e0 Antigua a un arr\u00eat final \u00e0 Guatemala City, o\u00f9 les passagers doivent monter dans une petite navette partag\u00e9e qui les emm\u00e8ne directement \u00e0 Antigua.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;4379&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Comment se rendre de Flores \u00e0 Antigua, au Guatemala.&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Rate this post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous pouvez vous rendre de Flores \u00e0 Antigua en navette partag\u00e9e, en bus de luxe, en transfert priv\u00e9 ou en&#8230;<\/p>\n","protected":false},"author":4,"featured_media":786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-4379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itineraires-au-guatemala"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/posts\/4379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":4,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"predecessor-version":[{"id":7942,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/posts\/4379\/revisions\/7942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/media\/786"}],"wp:attachment":[{"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guatemalatransportservice.com\/fr\/wp-json\/wp\/v2\/tags?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}